{"id":2439,"date":"2022-05-22T20:08:05","date_gmt":"2022-05-22T11:08:05","guid":{"rendered":"https:\/\/www.kokorosya.co.jp\/?post_type=event&amp;p=2439"},"modified":"2022-05-22T20:08:05","modified_gmt":"2022-05-22T11:08:05","slug":"study220605","status":"publish","type":"post","link":"https:\/\/www.kokorosya.co.jp\/event\/2022\/05\/22\/study220605\/","title":{"rendered":"\u30106\/5\u3011\u300c\u304a\u5bb6\u3065\u304f\u308a\u306e\u52c9\u5f37\u4f1a\u300d\u3092\u30db\u30eb\u30c8\u30db\u30fc\u30eb\u5927\u5206\u3067\u958b\u50ac\u3057\u307e\u3059\uff01"},"content":{"rendered":"<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<h2>&nbsp;<\/h2>\n<h2 class=\"full typesquare_tags typesquare_tags typesquare_tags\" style=\"text-align: center;\"><span style=\"font-size: 14pt;\">\u4f8b\u3048\u3070\u3001\u3053\u3093\u306a\u3053\u3068\u3067<\/span><\/h2>\n<h2 class=\"full typesquare_tags typesquare_tags typesquare_tags\" style=\"text-align: center;\"><span style=\"font-size: 14pt;\">\u56f0\u3063\u3066\u3044\u307e\u305b\u3093\u304b\uff1f<\/span><\/h2>\n<div>&nbsp;<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2452\" src=\"https:\/\/www.kokorosya.co.jp\/wp-content\/uploads\/2022\/05\/\u30b7\u30f3\u30d9\u30f3\u30ad\u30e7\u30a6\u30ab\u30a4\uff08LP\uff09.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.kokorosya.co.jp\/event\/wp-content\/uploads\/2022\/05\/\u30b7\u30f3\u30d9\u30f3\u30ad\u30e7\u30a6\u30ab\u30a4\uff08LP\uff09.jpg 1078w, https:\/\/www.kokorosya.co.jp\/event\/wp-content\/uploads\/2022\/05\/\u30b7\u30f3\u30d9\u30f3\u30ad\u30e7\u30a6\u30ab\u30a4\uff08LP\uff09-300x300.jpg 300w, https:\/\/www.kokorosya.co.jp\/event\/wp-content\/uploads\/2022\/05\/\u30b7\u30f3\u30d9\u30f3\u30ad\u30e7\u30a6\u30ab\u30a4\uff08LP\uff09-1024x1024.jpg 1024w, https:\/\/www.kokorosya.co.jp\/event\/wp-content\/uploads\/2022\/05\/\u30b7\u30f3\u30d9\u30f3\u30ad\u30e7\u30a6\u30ab\u30a4\uff08LP\uff09-150x150.jpg 150w, https:\/\/www.kokorosya.co.jp\/event\/wp-content\/uploads\/2022\/05\/\u30b7\u30f3\u30d9\u30f3\u30ad\u30e7\u30a6\u30ab\u30a4\uff08LP\uff09-768x768.jpg 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div>\n<div>&nbsp;<\/div>\n<div style=\"padding-left: 320px;\">&nbsp;<\/div>\n<div style=\"text-align: left;\">\n<div style=\"text-align: left;\">\u300c\u304a\u5bb6\u3065\u304f\u308a\u3063\u3066\u4f55\u304b\u3089\u59cb\u3081\u305f\u3089\u826f\u3044\u306e\u304b\u308f\u304b\u3089\u306a\u3044\u30fb\u30fb\u300d<\/div>\n<div style=\"text-align: left;\">\u300c\u8272\u3005\u3068\u898b\u305f\u3051\u3069\u30d4\u30f3\u3068\u6765\u306a\u3044\u30fb\u30fb\u300d<\/div>\n<div style=\"text-align: left;\">\u300c\u571f\u5730\u304c\u306a\u304b\u306a\u304b\u6c7a\u307e\u3089\u306a\u304f\u3066\u30fb\u30fb\u300d<\/div>\n<div style=\"text-align: left;\">&nbsp;<\/div>\n<div style=\"text-align: left;\">\u306a\u3069\u306a\u3069\u30fb\u30fb<\/div>\n<div style=\"text-align: left;\">&nbsp;<\/div>\n<\/div>\n<div>&nbsp;<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2247\" src=\"https:\/\/www.kokorosya.co.jp\/wp-content\/uploads\/2022\/02\/\u5206\u304b\u3089\u306a\u3044\uff01.jpg\" alt=\"\" width=\"600\" height=\"338\"><\/div>\n<div>\u300c\u4f55\u304c\u5206\u304b\u3089\u306a\u3044\u306e\u304b\u3082\u3001\u5206\u304b\u3089\u306a\u3044\u30fb\u30fb\u300d<\/div>\n<div>&nbsp;<\/div>\n<div>\u3068\u3044\u3046\u304a\u5bb6\u3065\u304f\u308a\u306e\u521d\u5fc3\u8005\u306e\u65b9\u5927\u6b53\u8fce\u3067\u3059\uff01<\/div>\n<div>&nbsp;<\/div>\n<div>\u300c\u3053\u3093\u306a\u3053\u3068\u805e\u3044\u3066\u3044\u3044\u306e\u304b\u306a\uff1f\u300d<\/div>\n<div>\u300c\u3053\u3093\u306a\u3053\u3068\u805e\u3044\u305f\u3089\u7b11\u308f\u308c\u308b\u304b\u3082\u30fb\u30fb\u300d<\/div>\n<div>&nbsp;<\/div>\n<div>\u3068\u3044\u3046\u3053\u3068\u3067\u3082\u3001\u4f55\u3067\u3082\u805e\u3044\u3066\u4e0b\u3055\u3044\u3002<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>\n<p style=\"text-align: left;\">\u3010\u65e5\u6642\u3011\u4ee4\u548c4\u5e746\u67085\u65e5\uff08\u65e5\uff09\u300013\uff1a00\uff5e16\uff1a00<\/p>\n<p><span style=\"font-size: 0.95em;\">\u3010\u5834\u6240\u3011\u30db\u30eb\u30c8\u30aa\u30fc\u30eb\u5927\u5206\u3000408\u4f1a\u8b70\u5ba4<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"full typesquare_tags typesquare_tags\">\n<p style=\"text-align: center;\">\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6<\/p>\n<\/div>\n<h3 style=\"text-align: center;\">\u3010\u3088\u304f\u3042\u308b\u8cea\u554f\u3011<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-978\" src=\"https:\/\/www.kokorosya.co.jp\/wp-content\/uploads\/2020\/11\/mente02-300x210.png\" alt=\"\u3059\u307e\u3044\u306e\u30d5\u30a3\u30c3\u30c6\u30a3\u30f3\u30b0\" width=\"300\" height=\"210\"><\/p>\n<div class=\"full typesquare_tags typesquare_tags\">\n<div class=\"full typesquare_tags typesquare_tags typesquare_tags\">\n<p style=\"text-align: left;\">\u25a1\u305d\u3082\u305d\u3082\u304a\u5bb6\u3092\u5efa\u3066\u305f\u307b\u3046\u304c\u3044\u3044\u306e\uff1f<\/p>\n<p style=\"text-align: left;\">\u25a1\u304a\u5bb6\u3065\u304f\u308a\u306e\u59cb\u3081\u65b9\u304c\u308f\u304b\u3089\u306a\u3044\uff01\uff01<\/p>\n<p>\u25a1\u5de5\u52d9\u5e97\u3068\u30cf\u30a6\u30b9\u30e1\u30fc\u30ab\u30fc\u306e\u9055\u3044\u3063\u3066\uff1f<\/p>\n<p style=\"text-align: left;\">\u25a1\u5efa\u3066\u308b\u306e\u306f\u6570\u5e74\u5f8c\u3060\u3051\u3069\u4eca\u306e\u3046\u3061\u304b\u3089\u3084\u3063\u3066\u304a\u3044\u305f\u307b\u3046\u304c\u3044\u3044\u3053\u3068\u3063\u3066\u30fb\u30fb\uff1f<\/p>\n<p style=\"text-align: left;\">\u306a\u3069\u306a\u3069\u30fb\u30fb<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6\u25c6<\/p>\n<h3 class=\"typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags\">\u3010\u3054\u4e88\u7d04\u65b9\u6cd5\u3011<\/h3>\n<p class=\"typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags\">\u30101\u3011\u3054\u5e0c\u671b\u306e\u65e5\u6642\u3092\u9078\u629e<\/p>\n<p class=\"typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags\">\u30102\u3011\u3054\u4e88\u7d04\u5185\u5bb9\u753b\u9762\u3067\u3001\u4e88\u7d04\u4eba\u6570\u3092\u300c1\u300d\u3067\u300c\u4e88\u7d04\u3059\u308b\u300d\u3092\u9078\u629e<\/p>\n<p class=\"typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags\">\u30103\u3011\u3054\u4e88\u7d04\u8005\u60c5\u5831\u306e\u5165\u529b\u753b\u9762\u3067\u3001\u60c5\u5831\u3092\u5165\u529b\u3057\u3066\u9032\u3080\u3068\u4e88\u7d04\u5b8c\u4e86\u3067\u3059\u3002<\/p>\n<p class=\"typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags typesquare_tags\">\u30104\u3011\u78ba\u8a8d\u30e1\u30fc\u30eb\u304c\u5c4a\u304d\u307e\u3059\u3002<\/p>\n<\/div>\n<p style=\"text-align: center;\">&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/airrsv.net\/kokorosya\/calendar\/embed\/\" width=\"100%\" height=\"1000px\" frameborder=\"0\"><\/iframe>    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; \u4f8b\u3048\u3070\u3001\u3053\u3093\u306a\u3053\u3068\u3067 \u56f0\u3063\u3066\u3044\u307e\u305b\u3093\u304b\uff1f &nbsp; &nbsp; &nbsp; \u300c\u304a\u5bb6\u3065\u304f\u308a\u3063\u3066\u4f55\u304b\u3089\u59cb\u3081\u305f\u3089\u826f\u3044\u306e\u304b\u308f\u304b\u3089\u306a\u3044\u30fb\u30fb\u300d \u300c\u8272\u3005\u3068\u898b\u305f\u3051\u3069\u30d4\u30f3\u3068\u6765\u306a\u3044\u30fb\u30fb\u300d \u300c [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-2439","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-4"},"_links":{"self":[{"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/posts\/2439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/comments?post=2439"}],"version-history":[{"count":0,"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/posts\/2439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/media\/2451"}],"wp:attachment":[{"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/media?parent=2439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/categories?post=2439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kokorosya.co.jp\/event\/wp-json\/wp\/v2\/tags?post=2439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}